{"id":7167,"date":"2026-03-18T17:23:08","date_gmt":"2026-03-18T20:23:08","guid":{"rendered":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/?page_id=7167"},"modified":"2026-04-24T09:49:51","modified_gmt":"2026-04-24T12:49:51","slug":"docentes-3","status":"publish","type":"page","link":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/docentes-3\/","title":{"rendered":"Docentes"},"content":{"rendered":"\n<ul>\n<li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/ofrecimientos-2\/\" data-type=\"URL\" data-id=\"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/ofrecimientos-2\/\" target=\"_blank\">Ofrecimientos<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8528,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/7167"}],"collection":[{"href":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/8528"}],"replies":[{"embeddable":true,"href":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=7167"}],"version-history":[{"count":4,"href":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/7167\/revisions"}],"predecessor-version":[{"id":7378,"href":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/7167\/revisions\/7378"}],"wp:attachment":[{"href":"https:\/\/ifdc3-juj.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=7167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}